{"id":1245,"date":"2022-05-23T16:16:17","date_gmt":"2022-05-23T14:16:17","guid":{"rendered":"https:\/\/motowalser.ch\/shop\/?post_type=product&#038;p=1245"},"modified":"2024-08-13T22:11:57","modified_gmt":"2024-08-13T20:11:57","slug":"pilot-handschuh-braun","status":"publish","type":"product","link":"https:\/\/motowalser.ch\/shop\/produkt\/pilot-handschuh-braun\/","title":{"rendered":"Pilot Handschuh Braun"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u2022 Sommerhandschuh aus 100 % hochwertigem, perforiertem Leder<br \/>\n\u2022 Weiche Eins\u00e4tze auf den Fingerkn\u00f6cheln und auf der Handfl \u00e4che.<br \/>\nKlettverschluss verstellbar<br \/>\n\u2022 thermoplastischer Kn\u00f6chelprotektor<\/p>\n","protected":false},"featured_media":1320,"template":"","meta":{"_links_to":"","_links_to_target":""},"product_cat":[59,62,44,45],"product_tag":[144,159,170,166],"acf":[],"_links":{"self":[{"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/product\/1245"}],"collection":[{"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/media\/1320"}],"wp:attachment":[{"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/media?parent=1245"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/product_cat?post=1245"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/motowalser.ch\/shop\/wp-json\/wp\/v2\/product_tag?post=1245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}